{"id":8279,"date":"2016-03-15T22:23:20","date_gmt":"2016-03-16T01:23:20","guid":{"rendered":"https:\/\/www.vivareal.com.br\/blog\/\/blog\/\/?p=7900"},"modified":"2022-08-01T17:40:13","modified_gmt":"2022-08-01T20:40:13","slug":"4-casas-de-filmes-famosos-que-existem-na-vida-real","status":"publish","type":"post","link":"https:\/\/www.vivareal.com.br\/blog\/curiosidades\/celebridades\/4-casas-de-filmes-famosos-que-existem-na-vida-real\/","title":{"rendered":"4 casas de filmes famosos que existem na vida real"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Quantas vezes ao ver filmes famosos voc\u00ea teve a curiosidade em saber distinguir um cen\u00e1rio de uma loca\u00e7\u00e3o da vida real? Esta quest\u00e3o confunde at\u00e9 mesmo os cin\u00e9filos. Afinal, o cuidado com os m\u00ednimos detalhes em cada cena faz com que a gente se confunda sobre o que existe e o que foi montado especificamente para fazer parte de uma produ\u00e7\u00e3o cinematogr\u00e1fica. Em alguns casos, inclusive, essas casas s\u00e3o t\u00e3o marcantes que \u00e9 comum sonharmos at\u00e9 mesmo em morar nelas ou em resid\u00eancias parecidas, n\u00e3o \u00e9 verdade?<br \/>\n<\/span><br \/>\nFomos em busca de quatro casas de filmes famosos que realmente existem na vida real. Uma \u00f3tima chance de refrescar a mem\u00f3ria e, quem sabe, at\u00e9 mesmo reencontrar a sua preferida:<\/p>\n<h3><b>1. De volta para o futuro (1985): a casa de Marty MCFly e sua fam\u00edlia na trilogia<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">Quem n\u00e3o se lembra da resid\u00eancia dos MCFly em De volta para o futuro? A casa do filme que marcou toda uma gera\u00e7\u00e3o e foi bastante relembrado em 2015 \u2013 ano que Marty MCFly (Michael J. Fox) chega ao futuro no segundo filme da trilogia) \u2013 \u00e9 real! Ela pode ser vista facilmente. Basta dar uma voltinha em uma das cidades mais conhecidas da Calif\u00f3rnia, nos Estados Unidos: Los Angeles. A moradia que se tornou loca\u00e7\u00e3o de um dos filmes mais famosos da d\u00e9cada de 80 est\u00e1 localizada \u00e0 Avenida Roslyndale, n\u00famero 9303, no bairro de Arleta.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Para quem n\u00e3o tem planos de deslocar at\u00e9 a terra do Tio Sam por agora, um tour pelo Google Maps \u00e9 suficiente para relembrar este cl\u00e1ssico do cinema.<\/span><\/p>\n<h3><b>2. Curtindo a vida adoidado (1986): a memor\u00e1vel mans\u00e3o do Cameron<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">Um outro cl\u00e1ssico da d\u00e9cada de 80, o filme Curtindo a vida adoidado tem como personagem principal Ferris Buller (<\/span><span style=\"font-weight: 400;\">Matthew Broderick), que decide tirar um dia de folga da escola e \u201ccurtir a vida adoidado\u201d juntamente ao seu melhor amigo e namorada. Na obra, Cameron Frye (Alan Ruck), o citado amigo de Ferris, \u00e9 propriet\u00e1rio n\u00e3o apenas da Ferrari que utilizam no \u201cdia de folga\u201d, mas tamb\u00e9m da memor\u00e1vel mans\u00e3o de vidro que deixa qualquer um de queixo ca\u00eddo!<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Al\u00e9m do encanto do lugar, a casa ainda \u00e9 lembrada por fazer parte de uma das cenas mais emocionantes do filme. Quem n\u00e3o se lembra da Ferrari voando por uma das paredes de vidro da mans\u00e3o, n\u00e3o \u00e9 mesmo?<\/span><br \/>\n<span style=\"font-weight: 400;\">O im\u00f3vel, localizado em Highland park (Illinois \u2013 Estados Unidos), foi posto \u00e0 venda em 2009 pelo valor de 2,35 milh\u00f5es de d\u00f3lares. Contudo, apenas foi vendido em 2014, pela pechincha de USD 1,06 milh\u00e3o.<\/span><\/p>\n<h3><b>3. Esqueceram de mim (1990): o cen\u00e1rio de Kevin e suas armadilhas<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">A hist\u00f3ria j\u00e1 \u00e9 mais do que conhecida, divertindo adultos e crian\u00e7as de v\u00e1rias gera\u00e7\u00f5es. Kevin McCallister (Macaulay Culkin) foi esquecido em plenas f\u00e9rias natalinas em casa (e que casa!), sozinho. Com apenas 8 anos, o garoto esbanja esperteza assumindo as r\u00e9deas da situa\u00e7\u00e3o. Cuida de sua pr\u00f3pria comida, roupa e at\u00e9 mesmo de sua prote\u00e7\u00e3o contra ladr\u00f5es, ponto central do enredo do filme.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Para suas armadilhas, Kevin utiliza bem o espa\u00e7o de sua casa, que conta com 14 quartos. Na vida real o im\u00f3vel est\u00e1 situado em Winnetka, Illinois e foi vendida em 2012, a muito custo, por pouco mais de USD 1,5 milh\u00e3o. Em 2015 a propriedade foi valorizada e chegou a valer mais de 2,4 milh\u00f5es de d\u00f3lares.<\/span><\/p>\n<h3><b>4. Sex and the City (2008): o local onde a colunista Bradshaw criava<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">De uma s\u00e9rie reconhecida e premiada \u00e0s telonas do cinema, sex and the City ainda \u00e9 citada como prefer\u00eancia mundial de muitas mulheres. Afinal, apesar de seus epis\u00f3dios terem ido ao ar entre 1998 e 2004, os dois filmes da s\u00e9rie foram produzidos anos depois (2008 e 2010), abrangendo tamb\u00e9m uma nova gera\u00e7\u00e3o.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O cantinho de inspira\u00e7\u00f5es e cria\u00e7\u00f5es da colunista Carrie Bradshaw antes de se casar com Mr. Big, seu grande amor na trama, era um mix entre o real e o cenogr\u00e1fico. A faixada da casa mostrada na s\u00e9rie, palco dos in\u00fameros looks que a personagem desfilava ao descer aqueles degraus, pode ser visitada por qualquer um em Nova Iorque, nos Estados Unidos. Ela est\u00e1 localizada no West Village, n\u00famero 66 da Perry Street (entre a Bleeker e W 4TH street). Pois \u00e9, ao contr\u00e1rio do que a s\u00e9rie e o filme diziam, o apartamento da Carrie n\u00e3o ficava no Upper East Side.<\/span><\/p>\n<p>Uma outra curiosidade \u00e9 que apenas a parte externa da casa real era utilizada. As cenas de Carrie dentro de casa eram parte cenogr\u00e1fica! Mas tudo bem&#8230;. Isso n\u00e3o tira a import\u00e2ncia do im\u00f3vel que, com cinco quartos, foi vendido no ano de 2012 pelo valor de US$ 9,85 milh\u00f5es.<br \/>\n<span style=\"font-weight: 400;\">Algumas destas loca\u00e7\u00f5es de filmes famosos aparenta o im\u00f3vel dos seus sonhos ou tem algum outro im\u00f3vel das telonas que te deixa com os olhos brilhando? Conte para a gente nos coment\u00e1rios! \ud83d\ude09<\/span><\/p>\n<div class=\"vivar-depois-do-conteudo\" id=\"vivar-780476170\"><a href=\"https:\/\/www.zapimoveis.com.br\/?itm_id=100002&#038;itm_source=www.vivareal.com.br\/blog\/&#038;itm_medium=banner_home&#038;itm_campaign=cobranding-zap-vivareal&#038;itm_content=banner_600x600&#038;itm_term=mobile\" target=\"_blank\" aria-label=\"BANNER_Cobranded_VIVA_ZAP_1024x380\"><img src=\"https:\/\/www.vivareal.com.br\/blog\/wp-content\/uploads\/2022\/10\/BANNER_Cobranded_VIVA_ZAP_1024x380-1.jpg\" alt=\"BANNER_Cobranded_VIVA_ZAP_1024x380\"  srcset=\"https:\/\/www.vivareal.com.br\/blog\/wp-content\/uploads\/2022\/10\/BANNER_Cobranded_VIVA_ZAP_1024x380-1.jpg 710w, https:\/\/www.vivareal.com.br\/blog\/wp-content\/uploads\/2022\/10\/BANNER_Cobranded_VIVA_ZAP_1024x380-1-500x185.jpg 500w\" sizes=\"(max-width: 710px) 100vw, 710px\" width=\"710\" height=\"263\"  style=\"display: inline-block;\" \/><\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>Quantas vezes ao ver filmes famosos voc\u00ea teve a curiosidade [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":12284,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[177],"tags":[],"class_list":["post-8279","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-celebridades"],"_links":{"self":[{"href":"https:\/\/www.vivareal.com.br\/blog\/wp-json\/wp\/v2\/posts\/8279","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vivareal.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vivareal.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vivareal.com.br\/blog\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vivareal.com.br\/blog\/wp-json\/wp\/v2\/comments?post=8279"}],"version-history":[{"count":0,"href":"https:\/\/www.vivareal.com.br\/blog\/wp-json\/wp\/v2\/posts\/8279\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vivareal.com.br\/blog\/wp-json\/wp\/v2\/media\/12284"}],"wp:attachment":[{"href":"https:\/\/www.vivareal.com.br\/blog\/wp-json\/wp\/v2\/media?parent=8279"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vivareal.com.br\/blog\/wp-json\/wp\/v2\/categories?post=8279"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vivareal.com.br\/blog\/wp-json\/wp\/v2\/tags?post=8279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}